{"id":2695,"date":"2024-11-21T15:04:29","date_gmt":"2024-11-21T13:04:29","guid":{"rendered":"https:\/\/olympvillas.com\/?p=2695"},"modified":"2024-11-21T15:22:11","modified_gmt":"2024-11-21T13:22:11","slug":"mozliwosc-pracy-dla-specjalisty-ds-gospodarstwa-domowego","status":"publish","type":"post","link":"https:\/\/olympvillas.com\/pl\/jobs\/job-opportunity-for-household-professional\/","title":{"rendered":"Profesjonalista w gospodarstwie domowym"},"content":{"rendered":"<style>.wp-block-kadence-advancedheading.kt-adv-heading2695_fc84cb-92, .wp-block-kadence-advancedheading.kt-adv-heading2695_fc84cb-92[data-kb-block=\"kb-adv-heading2695_fc84cb-92\"]{font-size:var(--global-kb-font-size-md, 1.25rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading2695_fc84cb-92 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading2695_fc84cb-92[data-kb-block=\"kb-adv-heading2695_fc84cb-92\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading2695_fc84cb-92 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading2695_fc84cb-92[data-kb-block=\"kb-adv-heading2695_fc84cb-92\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading2695_fc84cb-92 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading2695_fc84cb-92\">Ligion Trading Limited at Olymp Luxury Villas is seeking a dedicated and reliable <strong>Household Professional <\/strong>to join our team. This position offers the opportunity to work in a prestigious environment, ensuring the maintenance and smooth operation of luxury villas in a stunning coastal location.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading2695_5ec554-51, .wp-block-kadence-advancedheading.kt-adv-heading2695_5ec554-51[data-kb-block=\"kb-adv-heading2695_5ec554-51\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading2695_5ec554-51 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading2695_5ec554-51[data-kb-block=\"kb-adv-heading2695_5ec554-51\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading2695_5ec554-51 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading2695_5ec554-51[data-kb-block=\"kb-adv-heading2695_5ec554-51\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading2695_5ec554-51 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading2695_5ec554-51\"><strong>Key Responsibilities<\/strong><\/h2>\n\n\n\n<ul class=\"wp-block-list has--font-size\">\n<li>Maintain and oversee the upkeep of luxury villas, ensuring all maintenance work is completed promptly and to the highest standard.<\/li>\n\n\n\n<li>Gardening and landscaping to maintain the beauty of villa exteriors.<\/li>\n\n\n\n<li>Regular cleaning and maintenance of swimming pools.<\/li>\n\n\n\n<li>Oversee and maintain company vehicles.<\/li>\n\n\n\n<li>Act as a personal driver for the company as needed.<\/li>\n<\/ul>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading2695_a50509-1e, .wp-block-kadence-advancedheading.kt-adv-heading2695_a50509-1e[data-kb-block=\"kb-adv-heading2695_a50509-1e\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading2695_a50509-1e mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading2695_a50509-1e[data-kb-block=\"kb-adv-heading2695_a50509-1e\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading2695_a50509-1e img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading2695_a50509-1e[data-kb-block=\"kb-adv-heading2695_a50509-1e\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading2695_a50509-1e wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading2695_a50509-1e\">Qualifications and Skills<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Proficiency in <strong>Russian, English, and Greek<\/strong> is highly desirable.<\/li>\n\n\n\n<li>Previous experience in a similar role is an advantage.<\/li>\n\n\n\n<li>Strong attention to detail and commitment to maintaining high standards.<\/li>\n\n\n\n<li>A valid driver\u2019s license is required.<\/li>\n<\/ul>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading2695_875527-c6, .wp-block-kadence-advancedheading.kt-adv-heading2695_875527-c6[data-kb-block=\"kb-adv-heading2695_875527-c6\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading2695_875527-c6 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading2695_875527-c6[data-kb-block=\"kb-adv-heading2695_875527-c6\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading2695_875527-c6 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading2695_875527-c6[data-kb-block=\"kb-adv-heading2695_875527-c6\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading2695_875527-c6 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading2695_875527-c6\">What We Offer<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Salary:<\/strong> \u20ac1300 (per month) + performance bonus<\/li>\n\n\n\n<li><strong>Schedule:<\/strong> 40 hours per week.<\/li>\n\n\n\n<li><strong>Annual Leave:<\/strong> 21 days of paid vacation.<\/li>\n\n\n\n<li><strong>Benefits:<\/strong> Amazing team and professional environment<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Join a dynamic team at Olymp Luxury Villas and contribute to creating an exceptional experience for our esteemed guests.<\/p>\n\n\n<style>.kt-accordion-id2695_8598c9-9d .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:8px;}.kt-accordion-id2695_8598c9-9d .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;background:#ffffff;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-accordion-id2695_8598c9-9d > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:4px solid #f2f2f2;border-left:0px solid #f2f2f2;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#ffffff;color:var(--global-palette2, #2B6CB0);padding-top:14px;padding-right:10px;padding-bottom:6px;padding-left:16px;}.kt-accordion-id2695_8598c9-9d:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id2695_8598c9-9d:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette2, #2B6CB0);}.kt-accordion-id2695_8598c9-9d:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:var(--global-palette2, #2B6CB0);}.kt-accordion-id2695_8598c9-9d:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id2695_8598c9-9d:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:#ffffff;}.kt-accordion-id2695_8598c9-9d > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id2695_8598c9-9d .kt-blocks-accordion-header:focus-visible{color:#444444;background:#ffffff;border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id2695_8598c9-9d:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id2695_8598c9-9d:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id2695_8598c9-9d:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id2695_8598c9-9d:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#444444;}.kt-accordion-id2695_8598c9-9d:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id2695_8598c9-9d:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:#444444;}.kt-accordion-id2695_8598c9-9d:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id2695_8598c9-9d:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id2695_8598c9-9d:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id2695_8598c9-9d:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#ffffff;}.kt-accordion-id2695_8598c9-9d .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id2695_8598c9-9d > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:#333333;background:#ffffff;border-top-color:var(--global-palette1, #3182CE);border-top-style:solid;border-right-color:var(--global-palette1, #3182CE);border-right-style:solid;border-bottom-color:var(--global-palette1, #3182CE);border-bottom-style:solid;border-left-color:var(--global-palette1, #3182CE);border-left-style:solid;}.kt-accordion-id2695_8598c9-9d:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id2695_8598c9-9d:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#333333;}.kt-accordion-id2695_8598c9-9d:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:#333333;}.kt-accordion-id2695_8598c9-9d:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id2695_8598c9-9d:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#ffffff;}@media all and (max-width: 1024px){.kt-accordion-id2695_8598c9-9d .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id2695_8598c9-9d > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:4px solid #f2f2f2;border-left:0px solid #f2f2f2;}}@media all and (max-width: 1024px){.kt-accordion-id2695_8598c9-9d > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id2695_8598c9-9d .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id2695_8598c9-9d .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id2695_8598c9-9d > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:var(--global-palette1, #3182CE);border-top-style:solid;border-right-color:var(--global-palette1, #3182CE);border-right-style:solid;border-bottom-color:var(--global-palette1, #3182CE);border-bottom-style:solid;border-left-color:var(--global-palette1, #3182CE);border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id2695_8598c9-9d .kt-accordion-inner-wrap{display:block;}.kt-accordion-id2695_8598c9-9d .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:8px;}.kt-accordion-id2695_8598c9-9d .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}.kt-accordion-id2695_8598c9-9d > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:4px solid #f2f2f2;border-left:0px solid #f2f2f2;}.kt-accordion-id2695_8598c9-9d > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id2695_8598c9-9d .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id2695_8598c9-9d .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id2695_8598c9-9d > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:var(--global-palette1, #3182CE);border-top-style:solid;border-right-color:var(--global-palette1, #3182CE);border-right-style:solid;border-bottom-color:var(--global-palette1, #3182CE);border-bottom-style:solid;border-left-color:var(--global-palette1, #3182CE);border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id2695_8598c9-9d kt-accordion-has-2-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-none kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"true\" data-start-open=\"none\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-1 kt-pane2695_e158c1-45\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clipboard kt-btn-side-left\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M16 4h2a2 2 0 0 1 2 2v14a2 2 0 0 1-2 2H6a2 2 0 0 1-2-2V6a2 2 0 0 1 2-2h2\"\/><rect x=\"8\" y=\"2\" width=\"8\" height=\"4\" rx=\"1\" ry=\"1\"\/><\/svg><\/span><span class=\"kt-blocks-accordion-title\"><strong>Apply Now<\/strong><\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<div class=\"forminator-guttenberg\"><form id=\"forminator-module-888\" class=\"forminator-custom-form forminator-custom-form-888\" method=\"post\" data-forminator-render=\"0\" data-uid=\"6a979644ad45f\"><div role=\"alert\" aria-live=\"polite\" class=\"forminator-response-message forminator-error\" aria-hidden=\"true\"><\/div><\/form><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ligion Trading Limited w Olymp Luxury Villas poszukuje oddanego i niezawodnego specjalisty ds. gospodarstwa domowego, kt\u00f3ry do\u0142\u0105czy do naszego zespo\u0142u. Stanowisko to oferuje mo\u017cliwo\u015b\u0107 pracy w presti\u017cowym \u015brodowisku,...<\/p>","protected":false},"author":1,"featured_media":2730,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","pgc_sgb_lightbox_settings":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"default","_kad_post_sidebar_id":"","_kad_post_content_style":"default","_kad_post_vertical_padding":"","_kad_post_feature":"default","_kad_post_feature_position":"default","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[3],"tags":[5],"class_list":["post-2695","post","type-post","status-publish","format-standard","has-post-thumbnail","category-jobs","tag-jobs"],"taxonomy_info":{"category":[{"value":3,"label":"Careers at Olymp Luxury Villas"}],"post_tag":[{"value":5,"label":"jobs"}]},"featured_image_src_large":["https:\/\/mdns.olympvillas.com\/wp-content\/uploads\/2024\/11\/gardener-Custom-1024x683.jpg",1024,683,true],"author_info":{"display_name":"Olymp Luxury Villas","author_link":"https:\/\/olympvillas.com\/pl\/author\/eristavi\/"},"comment_info":0,"category_info":[{"term_id":3,"name":"Careers at Olymp Luxury Villas","slug":"jobs","term_group":0,"term_taxonomy_id":3,"taxonomy":"category","description":"Join our dedicated team at Olymp Villas and contribute to an unparalleled luxury experience set against the backdrop of Cyprus's stunning landscapes. Here, your work transcends the ordinary, fostering a sustainable future while creating unforgettable moments for our guests. Explore opportunities where your passion and our vision align, and together, let's shape the future of luxury hospitality.","parent":0,"count":4,"filter":"raw","cat_ID":3,"category_count":4,"category_description":"Join our dedicated team at Olymp Villas and contribute to an unparalleled luxury experience set against the backdrop of Cyprus's stunning landscapes. Here, your work transcends the ordinary, fostering a sustainable future while creating unforgettable moments for our guests. Explore opportunities where your passion and our vision align, and together, let's shape the future of luxury hospitality.","cat_name":"Careers at Olymp Luxury Villas","category_nicename":"jobs","category_parent":0}],"tag_info":[{"term_id":5,"name":"jobs","slug":"jobs","term_group":0,"term_taxonomy_id":5,"taxonomy":"post_tag","description":"","parent":0,"count":2,"filter":"raw"}],"_links":{"self":[{"href":"https:\/\/olympvillas.com\/pl\/wp-json\/wp\/v2\/posts\/2695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/olympvillas.com\/pl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/olympvillas.com\/pl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/olympvillas.com\/pl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/olympvillas.com\/pl\/wp-json\/wp\/v2\/comments?post=2695"}],"version-history":[{"count":0,"href":"https:\/\/olympvillas.com\/pl\/wp-json\/wp\/v2\/posts\/2695\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/olympvillas.com\/pl\/wp-json\/wp\/v2\/media\/2730"}],"wp:attachment":[{"href":"https:\/\/olympvillas.com\/pl\/wp-json\/wp\/v2\/media?parent=2695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/olympvillas.com\/pl\/wp-json\/wp\/v2\/categories?post=2695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/olympvillas.com\/pl\/wp-json\/wp\/v2\/tags?post=2695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}