{"id":5662,"date":"2026-01-24T15:42:42","date_gmt":"2026-01-24T13:42:42","guid":{"rendered":"https:\/\/olympvillas.com\/terms-and-conditions\/"},"modified":"2026-01-24T15:42:42","modified_gmt":"2026-01-24T13:42:42","slug":"bedingungen-und-konditionen","status":"publish","type":"page","link":"https:\/\/olympvillas.com\/de\/terms-and-conditions\/","title":{"rendered":"Allgemeine Gesch\u00e4ftsbedingungen"},"content":{"rendered":"<!-- This legal document was generated by Complianz Terms &amp; Conditions https:\/\/wordpress.org\/plugins\/complianz-terms-conditions -->\n<div id=\"cmplz-document\" class=\"cmplz-document cmplz-terms-conditions\"><p><i>Die Allgemeinen Gesch\u00e4ftsbedingungen wurden zuletzt am M\u00e4rz 5, 2026 aktualisiert<\/i><\/p><h2>1. Einf\u00fchrung<\/h2><p>Diese Allgemeinen Gesch\u00e4ftsbedingungen gelten f\u00fcr diese Website und f\u00fcr Transaktionen im Zusammenhang mit unseren Produkten und Dienstleistungen. Sie sind m\u00f6glicherweise an zus\u00e4tzliche Vertr\u00e4ge gebunden, die sich auf Ihre Beziehung zu uns oder auf Produkte oder Dienstleistungen beziehen, die Sie von uns erhalten. Wenn Bestimmungen der Zusatzvertr\u00e4ge mit Bestimmungen dieser Bedingungen in Konflikt stehen, haben die Bestimmungen dieser Zusatzvertr\u00e4ge Vorrang.<\/p><h2>2. Verbindlichkeit<\/h2><p>Durch die Registrierung, den Zugriff auf oder die anderweitige Nutzung dieser Website erkl\u00e4ren Sie sich damit einverstanden, an die nachstehenden Allgemeinen Gesch\u00e4ftsbedingungen gebunden zu sein. Die blo\u00dfe Nutzung dieser Website setzt die Kenntnis und Annahme dieser Allgemeinen Gesch\u00e4ftsbedingungen voraus. In bestimmten F\u00e4llen k\u00f6nnen wir Sie auch bitten, dem ausdr\u00fccklich zuzustimmen.<\/p><h2>3. Elektronische Kommunikation<\/h2><p>Durch die Nutzung dieser Website oder die Kommunikation mit uns auf elektronischem Wege erkl\u00e4rst du dich damit einverstanden und erkennst an, dass wir auf unserer Website elektronisch mit dir kommunizieren oder dir eine E-Mail senden k\u00f6nnen, und stimmst zu, dass alle Vereinbarungen, Mitteilungen, Offenlegungen und sonstigen Mitteilungen, die wir dir elektronisch zusenden, alle gesetzlichen Anforderungen erf\u00fcllen. Dies beinhaltet, ist aber nicht beschr\u00e4nkt auf, die Anforderung, dass solche Mitteilungen schriftlich erfolgen m\u00fcssen.<\/p><h2>4. Geistiges Eigentum<\/h2><p>Wir oder unsere Lizenzgeber besitzen und kontrollieren alle Urheberrechte und sonstigen Rechte an geistigem Eigentum auf der Website sowie die Daten, Informationen und sonstigen Ressourcen, die auf der Website angezeigt werden oder auf der Website zug\u00e4nglich sind.<\/p><p class=\"cmplz-subtitle\">4.1 Alle Rechte vorbehalten<\/p><p>Sofern bestimmte Inhalte nichts anderes vorschreiben, wird dir keine Lizenz oder ein anderes Recht unter Urheber-, Marken-, Patent- oder anderen Rechten an geistigem Eigentum gew\u00e4hrt. Dies bedeutet, dass du keine Ressourcen auf dieser Website verwendest, kopierst, reproduzierst, ausf\u00fchrst, anzeigst, verteilst, in ein elektronisches Medium einbettet, \u00e4nderst, zur\u00fcckentwickelst, dekompilierst, \u00fcbergibst, herunterl\u00e4dst, \u00fcbertragst, monetarisierst, verkaufst, vermarktest oder kommerzialisierst in jeglicher Form, ohne unsere vorherige schriftliche Genehmigung, au\u00dfer und nur insoweit, als dies in den Bestimmungen des zwingenden Rechts (wie dem Recht auf Zitat) anders festgelegt ist.<\/p><h2>5. Eigentum von Drittanbietern<\/h2><p>Unsere Webseite kann Hyperlinks oder andere Verweise auf Webseiten Dritter enthalten. Wir \u00fcberwachen oder \u00fcberpr\u00fcfen nicht den Inhalt von Webseiten Dritter, auf die von dieser Webseite aus verwiesen wird. Produkte oder Dienstleistungen, die von anderen Webseiten angeboten werden, unterliegen den Allgemeinen Gesch\u00e4ftsbedingungen dieser Dritten. Meinungen oder Materialien, die auf diesen Webseiten ge\u00e4u\u00dfert werden, werden von uns nicht unbedingt geteilt oder unterst\u00fctzt.<\/p><p>Wir sind nicht verantwortlich f\u00fcr die Datenschutzpraktiken oder Inhalte dieser Websites. Sie tragen alle Risiken, die mit der Nutzung dieser Websites und damit verbundener Dienste Dritter verbunden sind. Wir \u00fcbernehmen keine Verantwortung f\u00fcr Verluste oder Sch\u00e4den jeglicher Art, die sich aus der Weitergabe Ihrer personenbezogenen Daten an Dritte ergeben.<\/p><h2>6. Verantwortungsvoller Umgang<\/h2><p>Durch den Besuch unserer Website erkl\u00e4rst du dich damit einverstanden, diese nur f\u00fcr die Zwecke zu verwenden, die durch diese Bedingungen, zus\u00e4tzliche Vertr\u00e4ge mit uns sowie geltende Gesetze, Vorschriften und allgemein anerkannte Online-Praktiken und Branchenrichtlinien beabsichtigt und gestattet sind. Du darfst unsere Website oder Dienste nicht verwenden, um Material zu verwenden, zu ver\u00f6ffentlichen oder zu verbreiten, das aus b\u00f6sartiger Computersoftware besteht (oder mit dieser verlinkt ist). Verwende die auf unserer Website gesammelten Daten f\u00fcr Direktmarketingaktivit\u00e4ten oder f\u00fchre systematische oder automatisierte Datenerfassungsaktivit\u00e4ten auf oder in Bezug auf unsere Website durch.<\/p><p>Die Teilnahme an Aktivit\u00e4ten, die Sch\u00e4den an der Website verursachen oder verursachen k\u00f6nnen oder die Leistung, Verf\u00fcgbarkeit oder Zug\u00e4nglichkeit der Website beeintr\u00e4chtigen, ist strengstens untersagt.<\/p><h2>7. R\u00fcckerstattungs- und R\u00fcckgaberecht<\/h2><p class=\"cmplz-subtitle\">7.1 Widerrufsrecht<\/p><p>Sie haben das Recht, binnen vierzehn Tagen ohne Angabe von Gr\u00fcnden diesen Vertrag zu widerrufen.<\/p><p>Die Widerrufsfrist l\u00e4uft 14 Tage nach dem Tag des Vertragsschlusses ab.<\/p><p>Um Ihr Widerrufsrecht auszu\u00fcben, m\u00fcssen Sie uns mittels einer eindeutigen Erkl\u00e4rung \u00fcber Ihren Entschluss, diesen Vertrag zu widerrufen, informieren. Zu diesem Zweck k\u00f6nnen Sie das <a target=\"_blank\" href=\"https:\/\/olympvillas.com\/de\/\">Auszahlungsfunktion verf\u00fcgbar<\/a>.Sie k\u00f6nnen Ihren Entschluss, den Vertrag zu widerrufen, jedoch auch durch eine andere eindeutige Erkl\u00e4rung auf andere geeignete Weise zum Ausdruck bringen.<\/p><p>Wir werden Ihnen den Eingang eines solchen Widerrufs unverz\u00f6gert auf einem dauerhaften Datentr\u00e4ger (z. B. per E-Mail) best\u00e4tigen.<\/p><p>Um die Widerrufsfrist einzuhalten, reicht es aus, dass Sie Ihre Mitteilung \u00fcber die Aus\u00fcbung des Widerrufsrechts vor Ablauf der Widerrufsfrist absenden.<\/p><p class=\"cmplz-subtitle\">7.2 Auswirkungen des Widerrufs<\/p><p>Wenn Sie von diesem Vertrag zur\u00fccktreten, haben wir alle Zahlungen, die wir von Ihnen erhalten haben, unverz\u00fcglich und sp\u00e4testens ab demTag, an dem wir \u00fcber Ihre Entscheidung zum R\u00fccktritt von diesem Vertrag informiert werden, zur\u00fcckzuerstatten. Dies gilt einschlie\u00dflich der Lieferkosten, mit Ausnahme der zus\u00e4tzlichen Kosten, die sich daraus ergeben, dass Sie eine andere Art der Lieferung als die von uns angebotene, g\u00fcnstigste Standardlieferung gew\u00e4hlt haben. Wir werden diese R\u00fcckerstattung mit denselben Zahlungsmitteln vornehmen, die Sie bei der urspr\u00fcnglichen Transaktion verwendet haben, es sei denn, es wurde ausdr\u00fccklich etwas anderes mit Ihnen vereinbart. In keinem Fall werden Ihnen wegen dieser R\u00fcckerstattung Entgelte berechnet. <\/p><p>Wenn Sie vor Beginn der Widerrufsfrist mit der Leistungserbringung begonnen haben, zahlen Sie uns einen Betrag, der dem Umfang der bis zu diesem Zeitpunkt erbrachten Leistungen entspricht, verglichen mit dem Umfang der gesamten vertraglich vereinbarten Leistungen, bis Sie uns Ihren R\u00fccktritt von diesem Vertrag mitteilen.<\/p><p>Bitte beachten Sie, dass es einige gesetzliche Ausnahmen vom Widerrufsrecht gibt und einige Artikel daher nicht zur\u00fcckgegeben oder umgetauscht werden k\u00f6nnen. Wir werden Sie informieren, wenn dies in Ihrem speziellen Fall zutrifft.<\/p><h2>8. Ideeneinreichung<\/h2><p>Reiche keine Ideen, Erfindungen, urheberrechtlich gesch\u00fctzten Werke oder andere Informationen ein, die als dein geistiges Eigentum gelten und die du uns pr\u00e4sentieren m\u00f6chtest, es sei denn, wir haben zuvor eine Vereinbarung \u00fcber geistiges Eigentum oder eine Geheimhaltungsvereinbarung unterzeichnet. Wenn du uns dies ohne eine solche schriftliche Vereinbarung mitteilst, gew\u00e4hrst du uns eine weltweite, unwiderrufliche, nicht exklusive, lizenzgeb\u00fchrenfreie Lizenz zur Nutzung, Reproduktion, Speicherung, Anpassung, Ver\u00f6ffentlichung, \u00dcbersetzung und Verbreitung deiner Inhalte in bestehenden oder zuk\u00fcnftigen Medien. .<\/p><h2>9. Nutzungsbeendigung<\/h2><p>Wir k\u00f6nnen nach eigenem Ermessen den Zugriff auf die Website oder einen darauf befindlichen Service jederzeit vor\u00fcbergehend oder dauerhaft \u00e4ndern oder einstellen. Du erkl\u00e4rst dich damit einverstanden, dass wir weder dir noch Dritten gegen\u00fcber f\u00fcr solche \u00c4nderungen, Aussetzungen oder Unterbrechungen deines Zugriffs auf oder deiner Nutzung der Website oder von Inhalten, die du m\u00f6glicherweise auf der Website geteilt hast, haften. Du hast keinen Anspruch auf Entsch\u00e4digung oder sonstige Zahlung, selbst wenn bestimmte Funktionen, Einstellungen und\/oder Inhalte, die du beigesteuert hast oder auf die du dich verl\u00e4sst, dauerhaft verloren gehen. Du darfst keine Zugriffsbeschr\u00e4nkungsma\u00dfnahmen auf unserer Website umgehen oder versuchen, sie zu umgehen.<\/p><h2>10. Garantien und Haftung<\/h2><p>Durch nichts in diesem Abschnitt wird eine gesetzlich implizierte Garantie eingeschr\u00e4nkt oder ausgeschlossen, deren Einschr\u00e4nkung oder Ausschluss rechtswidrig w\u00e4re. Diese Website und alle Inhalte der Website werden \u201cwie sie sind\u201d und \u201cwie verf\u00fcgbar\u201d bereitgestellt und k\u00f6nnen Ungenauigkeiten oder Tippfehler enthalten. Wir lehnen ausdr\u00fccklich jegliche ausdr\u00fcckliche oder stillschweigende Gew\u00e4hrleistung jeglicher Art hinsichtlich der Verf\u00fcgbarkeit, Richtigkeit oder Vollst\u00e4ndigkeit des Inhalts ab. Wir \u00fcbernehmen keine Garantie daf\u00fcr, dass:<\/p><p><ul>\n                    <li>Diese Webseite oder unser Inhalt wird deinen Anforderungen entsprechen.<\/li>\n                    <li>Diese Website wird ununterbrochen, zeitnah, sicher oder fehlerfrei verf\u00fcgbar sein.<\/li>\n        <\/ul><\/p><p>Nichts auf dieser Website stellt eine rechtliche, finanzielle oder medizinische Beratung jeglicher Art dar oder soll diese darstellen. Wenn du eine Beratung ben\u00f6tigst, solltest du einen geeigneten Fachmann konsultieren.<\/p><p>Die folgenden Bestimmungen dieses Abschnitts gelten im gesetzlich zul\u00e4ssigen H\u00f6chstma\u00df und schr\u00e4nken unsere Haftung in Bezug auf Angelegenheiten, f\u00fcr die es unrechtm\u00e4\u00dfig w\u00e4re, unsere Haftung einzuschr\u00e4nken oder auszuschlie\u00dfen, nicht ein oder aus. In keinem Fall haften wir f\u00fcr direkte oder indirekte Sch\u00e4den (einschlie\u00dflich Sch\u00e4den f\u00fcr entgangenen Gewinn oder Umsatz, Verlust oder Besch\u00e4digung von Daten, Software oder Datenbank oder Verlust oder Besch\u00e4digung von Eigentum oder Daten), die Ihnen oder Dritten entstehen und die sich aus Ihrem Zugriff auf oder Ihrer Nutzung unserer Website ergeben.<\/p><p>Sofern in einem zus\u00e4tzlichen Vertrag nicht ausdr\u00fccklich etwas anderes bestimmt ist, haften wir dir gegen\u00fcber maximal f\u00fcr alle Sch\u00e4den, die aus der Website oder mit Produkten und Dienstleistungen entstehen oder damit in Verbindung stehen, die \u00fcber die Website vermarktet oder verkauft werden, unabh\u00e4ngig von der Form der rechtlichen Schritte, die eine Haftung auferlegen (sei es vertraglich, nach Billigkeit, Fahrl\u00e4ssigkeit, vors\u00e4tzlichem Verhalten, unerlaubter Handlung oder auf andere Weise) wird auf den Gesamtpreis begrenzt, den du an uns gezahlt hast, um solche Produkte oder Dienstleistungen zu kaufen oder die Website zu nutzen. Diese Begrenzung gilt insgesamt f\u00fcr alle deine Anspr\u00fcche, Handlungen und Klagegr\u00fcnde jeglicher Art und Art.<\/p><h2>11. Privatsph\u00e4re<\/h2><p>Um auf unsere Website und\/oder Dienstleistungen zugreifen zu k\u00f6nnen, musst du im Rahmen des Registrierungsprozesses m\u00f6glicherweise bestimmte Informationen \u00fcber dich selbst angeben. Du stimmst zu, dass alle von dir angegebenen Informationen immer genau, korrekt und aktuell sind.<\/p><p>Wir haben eine Richtlinie entwickelt, um eventuelle Datenschutzbedenken auszur\u00e4umen. F\u00fcr weitere Informationen siehe unsere <a href=\"https:\/\/olympvillas.com\/privacy\/\">Datenschutzerkl\u00e4rung<\/a> und unser <a href=\"https:\/\/olympvillas.com\/cookie-policy-eu\/\">Cookie-Richtlinie<\/a>.<\/p><h2>12. Exportbeschr\u00e4nkungen \/ Einhaltung von Gesetzen<\/h2><p>Der Zugriff auf die Website aus Gebieten oder L\u00e4ndern, in denen der Inhalt oder Kauf der auf der Website verkauften Produkte oder Dienstleistungen illegal ist, ist verboten. Sie d\u00fcrfen diese Website nicht unter Versto\u00df gegen die Exportgesetze und -bestimmungen von Zypern verwenden.<\/p><h2>13. Zuordnung<\/h2><p>Ohne unsere vorherige schriftliche Zustimmung d\u00fcrfen Sie Ihre Rechte und\/oder Pflichten aus diesen Gesch\u00e4ftsbedingungen weder ganz noch teilweise abtreten, \u00fcbertragen oder an Dritte weitergeben. Jede angebliche Abtretung, die gegen diesen Abschnitt verst\u00f6\u00dft, ist nichtig.<\/p><h2>14. Verst\u00f6\u00dfe gegen diese Allgemeinen Gesch\u00e4ftsbedingungen<\/h2><p>Ungeachtet unserer anderen Rechte aus diesen Allgemeinen Gesch\u00e4ftsbedingungen k\u00f6nnen wir, wenn du in irgendeiner Weise gegen diese Allgemeinen Gesch\u00e4ftsbedingungen verst\u00f6\u00dft, Ma\u00dfnahmen ergreifen, die wir f\u00fcr angemessen halten, um den Versto\u00df zu behandeln, einschlie\u00dflich der vor\u00fcbergehenden oder dauerhaften Sperrung deines Zugriffs auf die Website und mit der Kontaktaufnahme deines Internetdienstanbieter mit der Aufforderung deinen Zugang zur Website zu sperren und\/oder rechtliche Schritte gegen dich einzuleiten.<\/p><h2>15. Entsch\u00e4digung<\/h2><p>Sie erkl\u00e4ren sich damit einverstanden, uns von allen Anspr\u00fcchen, Verbindlichkeiten, Sch\u00e4den, Verlusten und Kosten freizustellen, zu verteidigen und schadlos zu halten, die sich aus Ihrem Versto\u00df gegen diese Allgemeinen Gesch\u00e4ftsbedingungen und geltende Gesetze, einschlie\u00dflich Rechten an geistigem Eigentum und Datenschutzrechten, ergeben. Sie erstatten uns umgehend alle unsere Sch\u00e4den, Verluste, Kosten und Ausgaben im Zusammenhang mit oder aus solchen Anspr\u00fcchen.<\/p><h2>16. Verzicht<\/h2><p>Das Vers\u00e4umnis, eine der Bestimmungen dieser Allgemeinen Gesch\u00e4ftsbedingungen und einer Vereinbarung durchzusetzen, oder das Vers\u00e4umnis, eine K\u00fcndigungsoption auszu\u00fcben, gilt nicht als Verzicht auf diese Bestimmungen und ber\u00fchrt nicht die G\u00fcltigkeit dieser Allgemeinen Gesch\u00e4ftsbedingungen oder einer dieser Vereinbarungen oder ein Teil davon oder das Recht danach, jede einzelne Bestimmung durchzusetzen.<\/p><h2>17. Sprache<\/h2><p>Diese Allgemeinen Gesch\u00e4ftsbedingungen werden ausschlie\u00dflich in Englisch interpretiert und ausgelegt.&nbsp;Alle Mitteilungen und Korrespondenzen werden ausschlie\u00dflich in dieser Sprache verfasst.<\/p><h2>18. Vollst\u00e4ndige Vereinbarung<\/h2><p>Diese Allgemeinen Gesch\u00e4ftsbedingungen, zusammen mit unseren <a href=\"https:\/\/olympvillas.com\/privacy\/\">Datenschutzerkl\u00e4rung<\/a> und <a href=\"https:\/\/olympvillas.com\/cookie-policy-eu\/\">Cookie-Richtlinie<\/a>, bilden die gesamte Vereinbarung zwischen Ihnen und Ligion Trading Limited in Bezug auf Ihre Nutzung dieser Website.<\/p><h2>19. Aktualisierung dieser AGB<\/h2><p>Wir k\u00f6nnen diese Allgemeinen Gesch\u00e4ftsbedingungen von Zeit zu Zeit aktualisieren. Du bist verpflichtet, diese Allgemeinen Gesch\u00e4ftsbedingungen regelm\u00e4\u00dfig auf \u00c4nderungen oder Aktualisierungen zu \u00fcberpr\u00fcfen. Das zu Beginn dieser Allgemeinen Gesch\u00e4ftsbedingungen angegebene Datum ist das letzte \u00dcberarbeitungsdatum. \u00c4nderungen dieser Allgemeinen Gesch\u00e4ftsbedingungen werden wirksam, sobald solche \u00c4nderungen auf dieser Website ver\u00f6ffentlicht werden. Deine fortgesetzte Nutzung dieser Website nach der Ver\u00f6ffentlichung von \u00c4nderungen oder Aktualisierungen gilt als Hinweis auf deine Zustimmung zur Einhaltung und Bindung dieser Allgemeinen Gesch\u00e4ftsbedingungen.<\/p><h2>20. Rechtswahl und Gerichtsstand<\/h2><p>Diese Allgemeinen Gesch\u00e4ftsbedingungen unterliegen den Gesetzen von Zypern.  F\u00fcr alle Streitigkeiten im Zusammenhang mit diesen Allgemeinen Gesch\u00e4ftsbedingungen sind die Gerichte von Zypern zust\u00e4ndig. Wenn ein Teil oder eine Bestimmung dieser Allgemeinen Gesch\u00e4ftsbedingungen von einem Gericht oder einer anderen Beh\u00f6rde als ung\u00fcltig und \/ oder nach geltendem Recht nicht durchsetzbar befunden wird, wird dieser Teil oder diese Bestimmung im maximal zul\u00e4ssigen Umfang ge\u00e4ndert, gel\u00f6scht und \/ oder durchgesetzt die Absicht dieser Allgemeinen Gesch\u00e4ftsbedingungen verwirklicht. Die \u00fcbrigen Bestimmungen bleiben unber\u00fchrt.<\/p><h2>21. Kontaktinformationen<\/h2><p>Diese Website geh\u00f6rt und wird betrieben von Ligion Trading Limited. .<\/p><p>Du kannst uns bez\u00fcglich dieser Gesch\u00e4ftsbedingungen schriftlich oder per E-Mail an die folgende Adresse kontaktieren: &#105;&#110;f&#111;&#064;&#111;&#108;y&#109;&#112;v&#105;&#108;&#108;as.&#099;om<br>Navpliou 15<\/p><h2>22. Herunterladen<\/h2><p>Du kannst auch <a href=\"https:\/\/olympvillas.com\/wp-content\/plugins\/complianz-terms-conditions\/download.php\">Herunterladen<\/a> unsere AGB als PDF.<\/p><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","pgc_sgb_lightbox_settings":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-5662","page","type-page","status-publish"],"taxonomy_info":[],"featured_image_src_large":false,"author_info":{"display_name":"Olymp Luxury Villas","author_link":"https:\/\/olympvillas.com\/de\/author\/eristavi\/"},"comment_info":0,"_links":{"self":[{"href":"https:\/\/olympvillas.com\/de\/wp-json\/wp\/v2\/pages\/5662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/olympvillas.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/olympvillas.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/olympvillas.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/olympvillas.com\/de\/wp-json\/wp\/v2\/comments?post=5662"}],"version-history":[{"count":0,"href":"https:\/\/olympvillas.com\/de\/wp-json\/wp\/v2\/pages\/5662\/revisions"}],"wp:attachment":[{"href":"https:\/\/olympvillas.com\/de\/wp-json\/wp\/v2\/media?parent=5662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}